{"id":19486,"date":"2022-10-11T07:16:00","date_gmt":"2022-10-11T07:16:00","guid":{"rendered":"https:\/\/baliwildlife.com\/encyclopedia\/%encyclopedia-category%\/stalk-eyed-flies-cyrtodiopsis-dalmanni\/"},"modified":"2022-10-11T07:16:00","modified_gmt":"2022-10-11T07:16:00","slug":"stalk-eyed-flies-cyrtodiopsis-dalmanni","status":"publish","type":"encyclopedia","link":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/lalat-nyamuk\/stalk-eyed-flies-cyrtodiopsis-dalmanni\/","title":{"rendered":"Stalk-eyed Flies"},"content":{"rendered":"<p class=\"p1\"><i>Cyrtodiopsis dalmanni <\/i>memiliki struktur memanjang ke arah lateral kepala yang disebut batang mata yang panjangnya bisa melebihi panjang badannya berkisar antara 4-17 mm. Batang mata pada lalat jantan lebih panjang dibandingkan betina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cyrtodiopsis dalmanni memiliki struktur memanjang ke arah lateral kepala yang disebut batang mata yang panjangnya bisa melebihi panjang badannya berkisar antara 4-17 mm. Batang mata pada lalat jantan lebih panjang dibandingkan betina.<\/p>\n","protected":false},"author":1,"featured_media":19480,"parent":0,"menu_order":1913,"template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"encyclopedia-category":[192,247,200],"class_list":["post-19486","encyclopedia","type-encyclopedia","status-publish","has-post-thumbnail","hentry","encyclopedia-category-hewan","encyclopedia-category-lalat-nyamuk","encyclopedia-category-serangga","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stalk-eyed Flies (Cyrtodiopsis dalmanni) - Bali Wildlife<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/lalat-nyamuk\/stalk-eyed-flies-cyrtodiopsis-dalmanni\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stalk-eyed Flies (Cyrtodiopsis dalmanni) - Bali Wildlife\" \/>\n<meta property=\"og:description\" content=\"Cyrtodiopsis dalmanni memiliki struktur memanjang ke arah lateral kepala yang disebut batang mata yang panjangnya bisa melebihi panjang badannya berkisar antara 4-17 mm. Batang mata pada lalat jantan lebih panjang dibandingkan betina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/lalat-nyamuk\/stalk-eyed-flies-cyrtodiopsis-dalmanni\/\" \/>\n<meta property=\"og:site_name\" content=\"Bali Wildlife\" \/>\n<meta property=\"og:image\" content=\"https:\/\/baliwildlife.com\/wp-content\/uploads\/2022\/10\/Cyrtodiopsis-dalmanni-by-Nick-Lambert-Source-iNaturalist.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1344\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/ensiklopedia\\\/hewan\\\/serangga\\\/lalat-nyamuk\\\/stalk-eyed-flies-cyrtodiopsis-dalmanni\\\/\",\"url\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/ensiklopedia\\\/hewan\\\/serangga\\\/lalat-nyamuk\\\/stalk-eyed-flies-cyrtodiopsis-dalmanni\\\/\",\"name\":\"Stalk-eyed Flies (Cyrtodiopsis dalmanni) - Bali Wildlife\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/ensiklopedia\\\/hewan\\\/serangga\\\/lalat-nyamuk\\\/stalk-eyed-flies-cyrtodiopsis-dalmanni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/ensiklopedia\\\/hewan\\\/serangga\\\/lalat-nyamuk\\\/stalk-eyed-flies-cyrtodiopsis-dalmanni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/baliwildlife.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Cyrtodiopsis-dalmanni-by-Nick-Lambert-Source-iNaturalist.jpeg\",\"datePublished\":\"2022-10-11T07:16:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/ensiklopedia\\\/hewan\\\/serangga\\\/lalat-nyamuk\\\/stalk-eyed-flies-cyrtodiopsis-dalmanni\\\/#breadcrumb\"},\"inLanguage\":\"id\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/baliwildlife.com\\\/id\\\/ensiklopedia\\\/hewan\\\/serangga\\\/lalat-nyamuk\\\/stalk-eyed-flies-cyrtodiopsis-dalmanni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/ensiklopedia\\\/hewan\\\/serangga\\\/lalat-nyamuk\\\/stalk-eyed-flies-cyrtodiopsis-dalmanni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/baliwildlife.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Cyrtodiopsis-dalmanni-by-Nick-Lambert-Source-iNaturalist.jpeg\",\"contentUrl\":\"https:\\\/\\\/baliwildlife.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Cyrtodiopsis-dalmanni-by-Nick-Lambert-Source-iNaturalist.jpeg\",\"width\":1920,\"height\":1344,\"caption\":\"Photo by Nick Lambert Source iNaturalist\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/ensiklopedia\\\/hewan\\\/serangga\\\/lalat-nyamuk\\\/stalk-eyed-flies-cyrtodiopsis-dalmanni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encyclopedia\",\"item\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/ensiklopedia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hewan\",\"item\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/encyclopedia\\\/encyclopedia-category\\\/hewan\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Serangga\",\"item\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/encyclopedia\\\/encyclopedia-category\\\/hewan\\\/serangga\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Lalat, Nyamuk\",\"item\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/encyclopedia\\\/encyclopedia-category\\\/hewan\\\/serangga\\\/lalat-nyamuk\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Stalk-eyed Flies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/#website\",\"url\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/\",\"name\":\"Bali Wildlife\",\"description\":\"Every Spices Matter\",\"publisher\":{\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/#organization\",\"name\":\"Bali Wildlife\",\"url\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/baliwildlife.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Bali-Wildlife-logo.png\",\"contentUrl\":\"https:\\\/\\\/baliwildlife.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Bali-Wildlife-logo.png\",\"width\":150,\"height\":35,\"caption\":\"Bali Wildlife\"},\"image\":{\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stalk-eyed Flies (Cyrtodiopsis dalmanni) - Bali Wildlife","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/lalat-nyamuk\/stalk-eyed-flies-cyrtodiopsis-dalmanni\/","og_locale":"id_ID","og_type":"article","og_title":"Stalk-eyed Flies (Cyrtodiopsis dalmanni) - Bali Wildlife","og_description":"Cyrtodiopsis dalmanni memiliki struktur memanjang ke arah lateral kepala yang disebut batang mata yang panjangnya bisa melebihi panjang badannya berkisar antara 4-17 mm. Batang mata pada lalat jantan lebih panjang dibandingkan betina.","og_url":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/lalat-nyamuk\/stalk-eyed-flies-cyrtodiopsis-dalmanni\/","og_site_name":"Bali Wildlife","og_image":[{"width":1920,"height":1344,"url":"https:\/\/baliwildlife.com\/wp-content\/uploads\/2022\/10\/Cyrtodiopsis-dalmanni-by-Nick-Lambert-Source-iNaturalist.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/lalat-nyamuk\/stalk-eyed-flies-cyrtodiopsis-dalmanni\/","url":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/lalat-nyamuk\/stalk-eyed-flies-cyrtodiopsis-dalmanni\/","name":"Stalk-eyed Flies (Cyrtodiopsis dalmanni) - Bali Wildlife","isPartOf":{"@id":"https:\/\/baliwildlife.com\/id\/#website"},"primaryImageOfPage":{"@id":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/lalat-nyamuk\/stalk-eyed-flies-cyrtodiopsis-dalmanni\/#primaryimage"},"image":{"@id":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/lalat-nyamuk\/stalk-eyed-flies-cyrtodiopsis-dalmanni\/#primaryimage"},"thumbnailUrl":"https:\/\/baliwildlife.com\/wp-content\/uploads\/2022\/10\/Cyrtodiopsis-dalmanni-by-Nick-Lambert-Source-iNaturalist.jpeg","datePublished":"2022-10-11T07:16:00+00:00","breadcrumb":{"@id":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/lalat-nyamuk\/stalk-eyed-flies-cyrtodiopsis-dalmanni\/#breadcrumb"},"inLanguage":"id","potentialAction":[{"@type":"ReadAction","target":["https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/lalat-nyamuk\/stalk-eyed-flies-cyrtodiopsis-dalmanni\/"]}]},{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/lalat-nyamuk\/stalk-eyed-flies-cyrtodiopsis-dalmanni\/#primaryimage","url":"https:\/\/baliwildlife.com\/wp-content\/uploads\/2022\/10\/Cyrtodiopsis-dalmanni-by-Nick-Lambert-Source-iNaturalist.jpeg","contentUrl":"https:\/\/baliwildlife.com\/wp-content\/uploads\/2022\/10\/Cyrtodiopsis-dalmanni-by-Nick-Lambert-Source-iNaturalist.jpeg","width":1920,"height":1344,"caption":"Photo by Nick Lambert Source iNaturalist"},{"@type":"BreadcrumbList","@id":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/lalat-nyamuk\/stalk-eyed-flies-cyrtodiopsis-dalmanni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/baliwildlife.com\/id\/"},{"@type":"ListItem","position":2,"name":"Encyclopedia","item":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/"},{"@type":"ListItem","position":3,"name":"Hewan","item":"https:\/\/baliwildlife.com\/id\/encyclopedia\/encyclopedia-category\/hewan\/"},{"@type":"ListItem","position":4,"name":"Serangga","item":"https:\/\/baliwildlife.com\/id\/encyclopedia\/encyclopedia-category\/hewan\/serangga\/"},{"@type":"ListItem","position":5,"name":"Lalat, Nyamuk","item":"https:\/\/baliwildlife.com\/id\/encyclopedia\/encyclopedia-category\/hewan\/serangga\/lalat-nyamuk\/"},{"@type":"ListItem","position":6,"name":"Stalk-eyed Flies"}]},{"@type":"WebSite","@id":"https:\/\/baliwildlife.com\/id\/#website","url":"https:\/\/baliwildlife.com\/id\/","name":"Bali Wildlife","description":"Every Spices Matter","publisher":{"@id":"https:\/\/baliwildlife.com\/id\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/baliwildlife.com\/id\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"},{"@type":"Organization","@id":"https:\/\/baliwildlife.com\/id\/#organization","name":"Bali Wildlife","url":"https:\/\/baliwildlife.com\/id\/","logo":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/baliwildlife.com\/id\/#\/schema\/logo\/image\/","url":"https:\/\/baliwildlife.com\/wp-content\/uploads\/2021\/04\/Bali-Wildlife-logo.png","contentUrl":"https:\/\/baliwildlife.com\/wp-content\/uploads\/2021\/04\/Bali-Wildlife-logo.png","width":150,"height":35,"caption":"Bali Wildlife"},"image":{"@id":"https:\/\/baliwildlife.com\/id\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/encyclopedia\/19486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/encyclopedia"}],"about":[{"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/types\/encyclopedia"}],"author":[{"embeddable":true,"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/encyclopedia\/19486\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/media\/19480"}],"wp:attachment":[{"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/media?parent=19486"}],"wp:term":[{"taxonomy":"encyclopedia-category","embeddable":true,"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/encyclopedia-category?post=19486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}