{"id":19449,"date":"2022-10-11T05:23:01","date_gmt":"2022-10-11T05:23:01","guid":{"rendered":"https:\/\/baliwildlife.com\/encyclopedia\/%encyclopedia-category%\/jeweled-flower-mantis-creobroter-gemmatus\/"},"modified":"2023-05-15T07:05:34","modified_gmt":"2023-05-15T07:05:34","slug":"jeweled-flower-mantis-creobroter-gemmatus","status":"publish","type":"encyclopedia","link":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/belalang-sembah\/jeweled-flower-mantis-creobroter-gemmatus\/","title":{"rendered":"Jeweled Flower Mantis"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":19437,"parent":0,"menu_order":1907,"template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"encyclopedia-category":[211,192,200],"class_list":["post-19449","encyclopedia","type-encyclopedia","status-publish","has-post-thumbnail","hentry","encyclopedia-category-belalang-sembah","encyclopedia-category-hewan","encyclopedia-category-serangga","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jeweled Flower Mantis (Creobroter gemmatus) - Bali Wildlife<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/belalang-sembah\/jeweled-flower-mantis-creobroter-gemmatus\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jeweled Flower Mantis (Creobroter gemmatus) - Bali Wildlife\" \/>\n<meta property=\"og:url\" content=\"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/belalang-sembah\/jeweled-flower-mantis-creobroter-gemmatus\/\" \/>\n<meta property=\"og:site_name\" content=\"Bali Wildlife\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-15T07:05:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/baliwildlife.com\/wp-content\/uploads\/2022\/10\/Jeweled-Flower-Mantis-Creobroter-gemmatus-photo-by-Aswad-Andriyanto-Source-iNaturalist.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1434\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/ensiklopedia\\\/hewan\\\/serangga\\\/belalang-sembah\\\/jeweled-flower-mantis-creobroter-gemmatus\\\/\",\"url\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/ensiklopedia\\\/hewan\\\/serangga\\\/belalang-sembah\\\/jeweled-flower-mantis-creobroter-gemmatus\\\/\",\"name\":\"Jeweled Flower Mantis (Creobroter gemmatus) - Bali Wildlife\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/ensiklopedia\\\/hewan\\\/serangga\\\/belalang-sembah\\\/jeweled-flower-mantis-creobroter-gemmatus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/ensiklopedia\\\/hewan\\\/serangga\\\/belalang-sembah\\\/jeweled-flower-mantis-creobroter-gemmatus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/baliwildlife.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Jeweled-Flower-Mantis-Creobroter-gemmatus-photo-by-Aswad-Andriyanto-Source-iNaturalist.jpeg\",\"datePublished\":\"2022-10-11T05:23:01+00:00\",\"dateModified\":\"2023-05-15T07:05:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/ensiklopedia\\\/hewan\\\/serangga\\\/belalang-sembah\\\/jeweled-flower-mantis-creobroter-gemmatus\\\/#breadcrumb\"},\"inLanguage\":\"id\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/baliwildlife.com\\\/id\\\/ensiklopedia\\\/hewan\\\/serangga\\\/belalang-sembah\\\/jeweled-flower-mantis-creobroter-gemmatus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/ensiklopedia\\\/hewan\\\/serangga\\\/belalang-sembah\\\/jeweled-flower-mantis-creobroter-gemmatus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/baliwildlife.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Jeweled-Flower-Mantis-Creobroter-gemmatus-photo-by-Aswad-Andriyanto-Source-iNaturalist.jpeg\",\"contentUrl\":\"https:\\\/\\\/baliwildlife.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Jeweled-Flower-Mantis-Creobroter-gemmatus-photo-by-Aswad-Andriyanto-Source-iNaturalist.jpeg\",\"width\":2048,\"height\":1434,\"caption\":\"Photo by Aswad Andriyanto, Source iNaturalist\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/ensiklopedia\\\/hewan\\\/serangga\\\/belalang-sembah\\\/jeweled-flower-mantis-creobroter-gemmatus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encyclopedia\",\"item\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/ensiklopedia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hewan\",\"item\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/encyclopedia\\\/encyclopedia-category\\\/hewan\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Serangga\",\"item\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/encyclopedia\\\/encyclopedia-category\\\/hewan\\\/serangga\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Belalang Sembah\",\"item\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/encyclopedia\\\/encyclopedia-category\\\/hewan\\\/serangga\\\/belalang-sembah\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Jeweled Flower Mantis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/#website\",\"url\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/\",\"name\":\"Bali Wildlife\",\"description\":\"Every Spices Matter\",\"publisher\":{\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/#organization\",\"name\":\"Bali Wildlife\",\"url\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/baliwildlife.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Bali-Wildlife-logo.png\",\"contentUrl\":\"https:\\\/\\\/baliwildlife.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Bali-Wildlife-logo.png\",\"width\":150,\"height\":35,\"caption\":\"Bali Wildlife\"},\"image\":{\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jeweled Flower Mantis (Creobroter gemmatus) - Bali Wildlife","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/belalang-sembah\/jeweled-flower-mantis-creobroter-gemmatus\/","og_locale":"id_ID","og_type":"article","og_title":"Jeweled Flower Mantis (Creobroter gemmatus) - Bali Wildlife","og_url":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/belalang-sembah\/jeweled-flower-mantis-creobroter-gemmatus\/","og_site_name":"Bali Wildlife","article_modified_time":"2023-05-15T07:05:34+00:00","og_image":[{"width":2048,"height":1434,"url":"https:\/\/baliwildlife.com\/wp-content\/uploads\/2022\/10\/Jeweled-Flower-Mantis-Creobroter-gemmatus-photo-by-Aswad-Andriyanto-Source-iNaturalist.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/belalang-sembah\/jeweled-flower-mantis-creobroter-gemmatus\/","url":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/belalang-sembah\/jeweled-flower-mantis-creobroter-gemmatus\/","name":"Jeweled Flower Mantis (Creobroter gemmatus) - Bali Wildlife","isPartOf":{"@id":"https:\/\/baliwildlife.com\/id\/#website"},"primaryImageOfPage":{"@id":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/belalang-sembah\/jeweled-flower-mantis-creobroter-gemmatus\/#primaryimage"},"image":{"@id":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/belalang-sembah\/jeweled-flower-mantis-creobroter-gemmatus\/#primaryimage"},"thumbnailUrl":"https:\/\/baliwildlife.com\/wp-content\/uploads\/2022\/10\/Jeweled-Flower-Mantis-Creobroter-gemmatus-photo-by-Aswad-Andriyanto-Source-iNaturalist.jpeg","datePublished":"2022-10-11T05:23:01+00:00","dateModified":"2023-05-15T07:05:34+00:00","breadcrumb":{"@id":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/belalang-sembah\/jeweled-flower-mantis-creobroter-gemmatus\/#breadcrumb"},"inLanguage":"id","potentialAction":[{"@type":"ReadAction","target":["https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/belalang-sembah\/jeweled-flower-mantis-creobroter-gemmatus\/"]}]},{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/belalang-sembah\/jeweled-flower-mantis-creobroter-gemmatus\/#primaryimage","url":"https:\/\/baliwildlife.com\/wp-content\/uploads\/2022\/10\/Jeweled-Flower-Mantis-Creobroter-gemmatus-photo-by-Aswad-Andriyanto-Source-iNaturalist.jpeg","contentUrl":"https:\/\/baliwildlife.com\/wp-content\/uploads\/2022\/10\/Jeweled-Flower-Mantis-Creobroter-gemmatus-photo-by-Aswad-Andriyanto-Source-iNaturalist.jpeg","width":2048,"height":1434,"caption":"Photo by Aswad Andriyanto, Source iNaturalist"},{"@type":"BreadcrumbList","@id":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/hewan\/serangga\/belalang-sembah\/jeweled-flower-mantis-creobroter-gemmatus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/baliwildlife.com\/id\/"},{"@type":"ListItem","position":2,"name":"Encyclopedia","item":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/"},{"@type":"ListItem","position":3,"name":"Hewan","item":"https:\/\/baliwildlife.com\/id\/encyclopedia\/encyclopedia-category\/hewan\/"},{"@type":"ListItem","position":4,"name":"Serangga","item":"https:\/\/baliwildlife.com\/id\/encyclopedia\/encyclopedia-category\/hewan\/serangga\/"},{"@type":"ListItem","position":5,"name":"Belalang Sembah","item":"https:\/\/baliwildlife.com\/id\/encyclopedia\/encyclopedia-category\/hewan\/serangga\/belalang-sembah\/"},{"@type":"ListItem","position":6,"name":"Jeweled Flower Mantis"}]},{"@type":"WebSite","@id":"https:\/\/baliwildlife.com\/id\/#website","url":"https:\/\/baliwildlife.com\/id\/","name":"Bali Wildlife","description":"Every Spices Matter","publisher":{"@id":"https:\/\/baliwildlife.com\/id\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/baliwildlife.com\/id\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"},{"@type":"Organization","@id":"https:\/\/baliwildlife.com\/id\/#organization","name":"Bali Wildlife","url":"https:\/\/baliwildlife.com\/id\/","logo":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/baliwildlife.com\/id\/#\/schema\/logo\/image\/","url":"https:\/\/baliwildlife.com\/wp-content\/uploads\/2021\/04\/Bali-Wildlife-logo.png","contentUrl":"https:\/\/baliwildlife.com\/wp-content\/uploads\/2021\/04\/Bali-Wildlife-logo.png","width":150,"height":35,"caption":"Bali Wildlife"},"image":{"@id":"https:\/\/baliwildlife.com\/id\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/encyclopedia\/19449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/encyclopedia"}],"about":[{"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/types\/encyclopedia"}],"author":[{"embeddable":true,"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/encyclopedia\/19449\/revisions"}],"predecessor-version":[{"id":21904,"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/encyclopedia\/19449\/revisions\/21904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/media\/19437"}],"wp:attachment":[{"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/media?parent=19449"}],"wp:term":[{"taxonomy":"encyclopedia-category","embeddable":true,"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/encyclopedia-category?post=19449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}