{"id":226,"count":4,"description":"Kalajengking merupakan hewan beruas dengan delapan kaki, tubuhnya dibagi menjadi 2 segmen yaitu cephalothorax dan abdomen. Semua spesies hewan ini berbisa dan termasuk neurotoksin (racun saraf). Bisa kalajengking kebanyakan tidak berbahaya bagi manusia, yaitu hanya menyebabkan pembengkakan dan rasa sakit. Namun beberapa spesies ada yang berbahaya dan menyebabkan kematian bagi manusia.","link":"https:\/\/baliwildlife.com\/id\/encyclopedia\/encyclopedia-category\/hewan\/kalajengking\/","name":"Kalajengking","slug":"kalajengking","taxonomy":"encyclopedia-category","parent":192,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kalajengking - Bali Wildlife<\/title>\n<meta name=\"description\" content=\"Scorpion is a segmented animal with eight legs, its body is divided into 2 segments, namely the cephalothorax and abdomen. All these animal species are venomous and include neurotoxins (nerve poison). Scorpion venom is mostly harmless to humans, which only causes swelling and pain. However, there are some species that are dangerous and cause death to humans.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/baliwildlife.com\/id\/encyclopedia\/encyclopedia-category\/hewan\/kalajengking\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kalajengking - Bali Wildlife\" \/>\n<meta property=\"og:description\" content=\"Scorpion is a segmented animal with eight legs, its body is divided into 2 segments, namely the cephalothorax and abdomen. All these animal species are venomous and include neurotoxins (nerve poison). Scorpion venom is mostly harmless to humans, which only causes swelling and pain. However, there are some species that are dangerous and cause death to humans.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/baliwildlife.com\/id\/encyclopedia\/encyclopedia-category\/hewan\/kalajengking\/\" \/>\n<meta property=\"og:site_name\" content=\"Bali Wildlife\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/encyclopedia\\\/encyclopedia-category\\\/hewan\\\/kalajengking\\\/\",\"url\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/encyclopedia\\\/encyclopedia-category\\\/hewan\\\/kalajengking\\\/\",\"name\":\"Kalajengking - Bali Wildlife\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/#website\"},\"description\":\"Scorpion is a segmented animal with eight legs, its body is divided into 2 segments, namely the cephalothorax and abdomen. All these animal species are venomous and include neurotoxins (nerve poison). Scorpion venom is mostly harmless to humans, which only causes swelling and pain. However, there are some species that are dangerous and cause death to humans.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/encyclopedia\\\/encyclopedia-category\\\/hewan\\\/kalajengking\\\/#breadcrumb\"},\"inLanguage\":\"id\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/encyclopedia\\\/encyclopedia-category\\\/hewan\\\/kalajengking\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encyclopedia\",\"item\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/ensiklopedia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hewan\",\"item\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/encyclopedia\\\/encyclopedia-category\\\/hewan\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Kalajengking\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/#website\",\"url\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/\",\"name\":\"Bali Wildlife\",\"description\":\"Every Spices Matter\",\"publisher\":{\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/#organization\",\"name\":\"Bali Wildlife\",\"url\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/baliwildlife.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Bali-Wildlife-logo.png\",\"contentUrl\":\"https:\\\/\\\/baliwildlife.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Bali-Wildlife-logo.png\",\"width\":150,\"height\":35,\"caption\":\"Bali Wildlife\"},\"image\":{\"@id\":\"https:\\\/\\\/baliwildlife.com\\\/id\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kalajengking - Bali Wildlife","description":"Scorpion is a segmented animal with eight legs, its body is divided into 2 segments, namely the cephalothorax and abdomen. All these animal species are venomous and include neurotoxins (nerve poison). Scorpion venom is mostly harmless to humans, which only causes swelling and pain. However, there are some species that are dangerous and cause death to humans.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/baliwildlife.com\/id\/encyclopedia\/encyclopedia-category\/hewan\/kalajengking\/","og_locale":"id_ID","og_type":"article","og_title":"Kalajengking - Bali Wildlife","og_description":"Scorpion is a segmented animal with eight legs, its body is divided into 2 segments, namely the cephalothorax and abdomen. All these animal species are venomous and include neurotoxins (nerve poison). Scorpion venom is mostly harmless to humans, which only causes swelling and pain. However, there are some species that are dangerous and cause death to humans.","og_url":"https:\/\/baliwildlife.com\/id\/encyclopedia\/encyclopedia-category\/hewan\/kalajengking\/","og_site_name":"Bali Wildlife","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/baliwildlife.com\/id\/encyclopedia\/encyclopedia-category\/hewan\/kalajengking\/","url":"https:\/\/baliwildlife.com\/id\/encyclopedia\/encyclopedia-category\/hewan\/kalajengking\/","name":"Kalajengking - Bali Wildlife","isPartOf":{"@id":"https:\/\/baliwildlife.com\/id\/#website"},"description":"Scorpion is a segmented animal with eight legs, its body is divided into 2 segments, namely the cephalothorax and abdomen. All these animal species are venomous and include neurotoxins (nerve poison). Scorpion venom is mostly harmless to humans, which only causes swelling and pain. However, there are some species that are dangerous and cause death to humans.","breadcrumb":{"@id":"https:\/\/baliwildlife.com\/id\/encyclopedia\/encyclopedia-category\/hewan\/kalajengking\/#breadcrumb"},"inLanguage":"id"},{"@type":"BreadcrumbList","@id":"https:\/\/baliwildlife.com\/id\/encyclopedia\/encyclopedia-category\/hewan\/kalajengking\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/baliwildlife.com\/id\/"},{"@type":"ListItem","position":2,"name":"Encyclopedia","item":"https:\/\/baliwildlife.com\/id\/ensiklopedia\/"},{"@type":"ListItem","position":3,"name":"Hewan","item":"https:\/\/baliwildlife.com\/id\/encyclopedia\/encyclopedia-category\/hewan\/"},{"@type":"ListItem","position":4,"name":"Kalajengking"}]},{"@type":"WebSite","@id":"https:\/\/baliwildlife.com\/id\/#website","url":"https:\/\/baliwildlife.com\/id\/","name":"Bali Wildlife","description":"Every Spices Matter","publisher":{"@id":"https:\/\/baliwildlife.com\/id\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/baliwildlife.com\/id\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"},{"@type":"Organization","@id":"https:\/\/baliwildlife.com\/id\/#organization","name":"Bali Wildlife","url":"https:\/\/baliwildlife.com\/id\/","logo":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/baliwildlife.com\/id\/#\/schema\/logo\/image\/","url":"https:\/\/baliwildlife.com\/wp-content\/uploads\/2021\/04\/Bali-Wildlife-logo.png","contentUrl":"https:\/\/baliwildlife.com\/wp-content\/uploads\/2021\/04\/Bali-Wildlife-logo.png","width":150,"height":35,"caption":"Bali Wildlife"},"image":{"@id":"https:\/\/baliwildlife.com\/id\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/encyclopedia-category\/226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/encyclopedia-category"}],"about":[{"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/taxonomies\/encyclopedia-category"}],"up":[{"embeddable":true,"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/encyclopedia-category\/192"}],"wp:post_type":[{"href":"https:\/\/baliwildlife.com\/id\/wp-json\/wp\/v2\/encyclopedia?encyclopedia-category=226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}